{"id":50,"count":3,"description":"","link":"https:\/\/www.beatingframe.com\/es\/categoria\/marketing-digital\/","name":"Marketing digital","slug":"marketing-digital","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marketing digital archivos - Andrea Quintero Colorado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.beatingframe.com\/en\/categoria\/marketing-digital\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marketing digital archivos - Andrea Quintero Colorado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.beatingframe.com\/es\/categoria\/marketing-digital\/\" \/>\n<meta property=\"og:site_name\" content=\"Andrea Quintero Colorado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marketing digital archivos - Andrea Quintero Colorado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.beatingframe.com\/en\/categoria\/marketing-digital\/","og_locale":"en_US","og_type":"article","og_title":"Marketing digital archivos - Andrea Quintero Colorado","og_url":"https:\/\/www.beatingframe.com\/es\/categoria\/marketing-digital\/","og_site_name":"Andrea Quintero Colorado","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.beatingframe.com\/es\/categoria\/marketing-digital\/","url":"https:\/\/www.beatingframe.com\/es\/categoria\/marketing-digital\/","name":"Marketing digital archivos - Andrea Quintero Colorado","isPartOf":{"@id":"https:\/\/www.beatingframe.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.beatingframe.com\/es\/categoria\/marketing-digital\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.beatingframe.com\/es\/categoria\/marketing-digital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.beatingframe.com\/en\/"},{"@type":"ListItem","position":2,"name":"Marketing digital"}]},{"@type":"WebSite","@id":"https:\/\/www.beatingframe.com\/en\/#website","url":"https:\/\/www.beatingframe.com\/en\/","name":"Andrea Quintero Colorado","description":"Turning meaningful events into storytelling systems that last","publisher":{"@id":"https:\/\/www.beatingframe.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.beatingframe.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.beatingframe.com\/en\/#organization","name":"Andrea Quintero Colorado","url":"https:\/\/www.beatingframe.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.beatingframe.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.beatingframe.com\/wp-content\/uploads\/2024\/09\/0-1-1-e1730896978881.jpg","contentUrl":"https:\/\/www.beatingframe.com\/wp-content\/uploads\/2024\/09\/0-1-1-e1730896978881.jpg","width":563,"height":258,"caption":"Andrea Quintero Colorado"},"image":{"@id":"https:\/\/www.beatingframe.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.beatingframe.com\/en\/wp-json\/wp\/v2\/categories\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.beatingframe.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.beatingframe.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.beatingframe.com\/en\/wp-json\/wp\/v2\/posts?categories=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}